{"id":23534,"date":"2023-11-10T10:17:15","date_gmt":"2023-11-10T10:17:15","guid":{"rendered":"https:\/\/www.visitsoglianoalrubicone.it\/nove-colli-2024\/"},"modified":"2024-12-06T10:21:44","modified_gmt":"2024-12-06T10:21:44","slug":"nove-colli-2024","status":"publish","type":"post","link":"https:\/\/www.visitsoglianoalrubicone.it\/de\/nove-colli-2024\/","title":{"rendered":"Nove Colli 2024"},"content":{"rendered":"<p>[vc_row full_width=&#8220;stretch_row_content_no_spaces&#8220;][vc_column][vc_single_image image=&#8220;22267&#8243; img_size=&#8220;1920 x 450&#8243; alignment=&#8220;center&#8220; el_class=&#8220;infotronik_banner_pagina&#8220;]\n\t\t\t<section class=\"do-normal-page-title-section\">\n\t\t\t\t<div class=\"container\">\n\t\t\t\t\t<div class=\"row uppercase\">\n\t\t\t\n\t\t\t\t\t\t<div class=\"do-page-title-wrapper\">\n\t\t\t\t\t\t\t<div class=\"do-default-page-title col-md-7 col-sm-7 col-xs-12\">\n\t\t\t\t\t\t\t\t<h2 info=15 class=\"infotronik_page_title_big\">Nove Colli 2024<\/h2>\n\t\t\t\t\t\t\t\t<p><\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"do-breadcumb\"><ul><\/ul><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/section>\n\t\t[vc_empty_space height=&#8220;20px&#8220;][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<p>\n<strong>Periodo:<\/strong> Domenica 19 maggio 2024<br\/><strong>Luogo: <\/strong>Partenza da Cesenatico &#8211; Lungo le strade del territorio di Sogliano<br\/><strong>Info:<\/strong> Tel.: +39 0547 672156 &#8211; <a href=\"mailto:info@novecolli.it\">info@novecolli.it<\/a><br\/><strong>Iscrizioni &amp; percorso:<\/strong> <a href=\"https:\/\/www.novecolli.it\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.novecolli.it\/<\/a>&#13;\n<p>Sportliches Ereignis im Stra\u00dfenradsport.<\/p>&#13;\n<p>Die Nove Colli 2024 r\u00fccken n\u00e4her, und das mit einer guten Nachricht, denn nun ist es offiziell, dass das Rennen nach den \u00c4nderungen an der Strecke der Ausgabe 2023, die durch die Sch\u00e4den des Hochwassers im vergangenen Mai diktiert wurden, auf seine ikonischsten Stra\u00dfen zur\u00fcckkehren wird. Es waren Monate der Arbeit, der technischen Besprechungen und der Bem\u00fchungen von Fausto Coppi zusammen mit den verschiedenen lokalen Verwaltungen, die an einem Rennen beteiligt sind, das auch ein Fest f\u00fcr die gesamte Romagna ist. Wir kehren also zur &#8218;urspr\u00fcnglichen&#8216; Strecke mit Charme und Tradition zur\u00fcck, die am Sonntag, den 19. Mai 2024, die Protagonisten sein werden. Die Strecken Die sogenannte &#8218;lange&#8216; Strecke umfasst insgesamt 194 km mit einem H\u00f6henunterschied von 3880 Metern. Sie beginnt an der Strandpromenade von Cesenatico und f\u00fchrt \u00fcber die traditionellen neun H\u00fcgel: Polenta, Pieve di Rivoschio, Ciola, Barbotto, Montetiffi, Perticara, Pugliano, Passo delle Siepi und Sogliano, bevor sie nach Cesenatico zur\u00fcckkehrt. Die so genannte &#8218;mittlere&#8216; Route im ersten Teil entspricht der langen Route bis zur Kreuzung zwischen den beiden Routen bei Kilometer 95 nach dem Anstieg von Barbotto. Die andere Route &#8211; eine wunderbare Neuheit der Ausgabe 2023 &#8211; best\u00e4tigt ihre freundliche Distanz von 60 km mit einem H\u00f6henunterschied von 650 Metern und den Passagen von Schloss Ribano, Sogliano, Savignano und der Cioca-Abfahrt mit ihren 18 Haarnadelkurven, die sie in aller Munde als das &#8222;kleine Stilfser Joch&#8220; bekannt gemacht haben.      <\/p>&#13;\n<p>[\/vc_column_text][vc_empty_space height=&#8220;20px&#8220;][vc_single_image image=&#8220;23539&#8243; img_size=&#8220;full&#8220; alignment=&#8220;center&#8220; onclick=&#8220;link_image&#8220;][vc_single_image image=&#8220;23540&#8243; img_size=&#8220;full&#8220; alignment=&#8220;center&#8220; onclick=&#8220;link_image&#8220;][vc_empty_space height=&#8220;20px&#8220;][vc_single_image image=&#8220;23536&#8243; img_size=&#8220;full&#8220; alignment=&#8220;center&#8220; onclick=&#8220;link_image&#8220;][vc_single_image image=&#8220;23537&#8243; img_size=&#8220;full&#8220; alignment=&#8220;center&#8220; onclick=&#8220;link_image&#8220;][vc_single_image image=&#8220;23538&#8243; img_size=&#8220;full&#8220; alignment=&#8220;center&#8220; onclick=&#8220;link_image&#8220;][vc_empty_space height=&#8220;20px&#8220;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8220;stretch_row_content_no_spaces&#8220;][vc_column][vc_single_image image=&#8220;22267&#8243; img_size=&#8220;1920 x 450&#8243; alignment=&#8220;center&#8220; el_class=&#8220;infotronik_banner_pagina&#8220;][vc_empty_space height=&#8220;20px&#8220;][vc_row_inner][vc_column_inner][vc_column_text] Periodo: Domenica 19 maggio 2024Luogo: Partenza da Cesenatico &#8211; Lungo le strade&#8230;<\/p>\n","protected":false},"author":3,"featured_media":21563,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"loftloader_page_shortcode":""},"categories":[821,843],"tags":[1048,1115,823,1114,827],"_links":{"self":[{"href":"https:\/\/www.visitsoglianoalrubicone.it\/de\/wp-json\/wp\/v2\/posts\/23534"}],"collection":[{"href":"https:\/\/www.visitsoglianoalrubicone.it\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.visitsoglianoalrubicone.it\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.visitsoglianoalrubicone.it\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.visitsoglianoalrubicone.it\/de\/wp-json\/wp\/v2\/comments?post=23534"}],"version-history":[{"count":2,"href":"https:\/\/www.visitsoglianoalrubicone.it\/de\/wp-json\/wp\/v2\/posts\/23534\/revisions"}],"predecessor-version":[{"id":23605,"href":"https:\/\/www.visitsoglianoalrubicone.it\/de\/wp-json\/wp\/v2\/posts\/23534\/revisions\/23605"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.visitsoglianoalrubicone.it\/de\/wp-json\/wp\/v2\/media\/21563"}],"wp:attachment":[{"href":"https:\/\/www.visitsoglianoalrubicone.it\/de\/wp-json\/wp\/v2\/media?parent=23534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.visitsoglianoalrubicone.it\/de\/wp-json\/wp\/v2\/categories?post=23534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.visitsoglianoalrubicone.it\/de\/wp-json\/wp\/v2\/tags?post=23534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}